
{"id":12355,"date":"2016-08-31T13:06:35","date_gmt":"2016-08-31T11:06:35","guid":{"rendered":"https:\/\/www.brickrknowledge.de\/es\/?page_id=12355"},"modified":"2017-07-27T13:41:02","modified_gmt":"2017-07-27T11:41:02","slug":"mhz-diy-set","status":"publish","type":"page","link":"https:\/\/wiki.brickrknowledge.com\/es\/sets\/diy\/mhz-diy-set\/","title":{"rendered":"Set DIY MHz"},"content":{"rendered":"\n\t\n\t<div class=\"container\" style=\"margin-top: 43px; margin-bottom: 43px;\">\n\t\t<div class=\"row\">\n\n\t\t\t\t\t\t\t<div class=\"col-sm-2 col-xs-6\">\n\t\t\t\t\t<img decoding=\"async\" class=\"img-responsive\" src=\"\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"col-sm-2 col-xs-6\">\n\t\t\t\t\t<img decoding=\"async\" class=\"img-responsive\" src=\"\" \/>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"col-sm-2 col-xs-6\">\n\t\t\t\t\t<img decoding=\"async\" class=\"img-responsive\" src=\"\" \/>\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\t<\/div>\n\n\n\t\n<p>El Set DIY MHz contiene todo lo que se necesita para realizar circuitos ambiciosos en el rango de MHz. El Set incluye 4 placas, de las cuales 1 lleva Roger RO4350 de alta calidad. Las placas FR4 son adecuadas para hasta 2,4GHz. Las diferentes placas se pueden utilizar para construir splitter, combinadores, filtros, mezcladores, adaptadores, atenuadores, alimentaci\u00f3n de sesgo o como elemento de conexi\u00f3n pasivo. Las l\u00edneas est\u00e1n dise\u00f1adas seg\u00fan Microstrip para 50Ohm. Todas las placas incluyen una rejilla adecuada para que se puedan combinar con Bricks terminados de nuestro sistema. En la mayor\u00eda de las placas se puede incorporar en la parte de abajo un regulador de tensi\u00f3n. El Set incluye conectores hembra BNC y P-SMP con diferentes conectores. Varias carcasas de pl\u00e1stico y metal completan el Set.<\/p>\n\n\t\n\n\t<div class=\"download_container category_container clearfix\" style=\"width: 400px; margin-top: 48px; margin-bottom: 48px; float: left; margin-right: 24px; min-height: 340px !important;\">\n\n\t\t<div class=\"download_thumb\" style=\"float:left; width: 50px;\">\n\t\t\t<a href=\"\/content\/uploads\/2016\/06\/MHz_Manual.pdf\" target=\"_blank\" style=\"text-transform: uppercase;\"><i class=\"fa fa-file-pdf-o fa-4x\"><\/i><\/a>\n\t\t<\/div>\n\n\t\t<div class=\"download_content\" style=\"float: left; margin-left: 30px; width: 280px;\">\n\t\t\t<h3 style=\"margin-top: 0;\">Manual alem\u00e1n Set DIY MHz<\/h3>\n\t\t\t<p>El manual del Set DIY MHz contiene las explicaciones de las placas incluidas en el mismo. Tus exprimentos MHz no tienen l\u00edmites!<\/p>\n\n\n\t\t\t<a href=\"\/content\/uploads\/2016\/06\/MHz_Manual.pdf\" target=\"_blank\" style=\"text-transform: uppercase;\">>> Download now<\/a>\n\t\t<\/div>\n\t<\/div>\n\n\n\n\t\n\n\t\n\t<div class=\"download_container category_container clearfix\" style=\"width: 400px; margin-top: 48px; margin-bottom: 48px; float: left; margin-right: 24px; min-height: 340px !important;\">\n\n\t\t<div class=\"download_thumb\" style=\"float:left; width: 50px;\">\n\t\t\t<a href=\"130192.html\" target=\"_blank\"><i class=\"fa fa-cart-plus fa-4x\"><\/i><\/a>\n\t\t<\/div>\n\n\t\t<div class=\"download_content\" style=\"float: left; margin-left: 30px; width: 280px;\">\n\t\t\t<h3 style=\"margin-top: 0;\">Set DIY MHz - En la tienda<\/h3>\n\t\t\t<p>\n\t\t\t\t\t\t\t<\/p>\n\n\t\t\t<p>\n\t\t\t\t<strong>Art.-ID:<\/strong> 130192<br \/>\n\t\t\t\t<strong>Manufacturer-ID:<\/strong> ALL-BRICK-0457<br \/>\n\t\t\t\t<strong>EAN-Code:<\/strong>  4038816130198<br \/><br \/><br \/>\n\t\t\t<\/p>\n\n\t\t\t<a href=\"https:\/\/shop.maker-store.de\/ArtByOrdernumber\/forward\/article\/130192\" target=\"_blank\">>> Order now<\/a>\n\t\t<\/div>\n\t<\/div>\n\n\n\t\n\n\t<div class=\"container\" style=\"margin-top: 43px; clear: both;\">\n\t\t<div class=\"row\">\n\n\t\t\t\n\n\n\n\n\n\t    <div class=\"container\" style=\"padding-bottom: 64px;\">\n        <div class=\"row\">\n\n\t\t\t\n\t\t\t\t\n                <div class=\"col-lg-2 col-md-4 col-xs-6\" style=\"margin-bottom: 16px;\">\n                    <div class=\"flip-container\" ontouchstart=\"this.classList.toggle('hover');\" style=\"text-align: center;\">\n                        <div class=\"flipper\">\n                            <div class=\"front\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto;\">\n\n                                    <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/wiki.brickrknowledge.com\/content\/uploads\/2015\/04\/Pic_ALL-BRICK-01411-150x150.jpg\" alt=\"\"\/>\n\n\n                                <\/div> <!--\/ .productImg -->\n\n                                <div class=\"productText\" style=\"margin-top: 16px;\">\n                                    <span class=\"amount\">\n\t\t\t\t\t\t\t\t\t\tx\t\t\t\t\t\t\t\t\t<\/span>\n\n                                    <h4 style=\"margin-top: 0; font-size: 14px;\">\n\t\t\t\t\t\t\t\t\t\tCarcasa pl\u00e1stico azul 1&#215;1                                    <\/h4>\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .front -->\n\n                            <div class=\"back\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto 16px auto;\">\n\t\t\t\t\t\t\t\t\t                                        <img decoding=\"async\" class=\"img-responsive\" src=\"\" alt=\" - Art.-ID: 116137\" style=\"margin: 0 auto;\" \/>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                <\/div>\n\n                                <div class=\"productText\" style=\"\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t                                            <a href=\"https:\/\/shop.maker-store.de\/ArtByOrdernumber\/forward\/article\/116137\" target=\"_blank\">\n                                                <i class=\"icon ion-ios-cart-outline\" style=\"font-size: 28px;\"><\/i>\n                                            <\/a>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n                                    <a href=\"#inline\" id=\"11465\" class=\"icon ion-ios-search brick_more\" style=\"font-size: 28px;\"><\/a>\n                                    <!--<a href=\"#scheme\" id=\"scheme_11465\" class=\"icon ion-wrench brick_scheme\" style=\"font-size: 24px;\"><\/a>-->\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .back -->\n                        <\/div> <!--\/ .flipper -->\n\n                    <\/div> <!--\/ .flip-container -->\n                <\/div> <!--\/ .col-sm-2 -->\n\n\t\t\t\n\t\t\t\t\n                <div class=\"col-lg-2 col-md-4 col-xs-6\" style=\"margin-bottom: 16px;\">\n                    <div class=\"flip-container\" ontouchstart=\"this.classList.toggle('hover');\" style=\"text-align: center;\">\n                        <div class=\"flipper\">\n                            <div class=\"front\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto;\">\n\n                                    <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/wiki.brickrknowledge.com\/content\/uploads\/2015\/04\/Pic_ALL-BRICK-01421-150x150.jpg\" alt=\"\"\/>\n\n\n                                <\/div> <!--\/ .productImg -->\n\n                                <div class=\"productText\" style=\"margin-top: 16px;\">\n                                    <span class=\"amount\">\n\t\t\t\t\t\t\t\t\t\tx\t\t\t\t\t\t\t\t\t<\/span>\n\n                                    <h4 style=\"margin-top: 0; font-size: 14px;\">\n\t\t\t\t\t\t\t\t\t\tCarcasa pl\u00e1stico negro 1&#215;1                                    <\/h4>\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .front -->\n\n                            <div class=\"back\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto 16px auto;\">\n\t\t\t\t\t\t\t\t\t                                        <img decoding=\"async\" class=\"img-responsive\" src=\"\" alt=\" - Art.-ID: 116138\" style=\"margin: 0 auto;\" \/>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                <\/div>\n\n                                <div class=\"productText\" style=\"\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t                                            <a href=\"https:\/\/shop.maker-store.de\/ArtByOrdernumber\/forward\/article\/116138\" target=\"_blank\">\n                                                <i class=\"icon ion-ios-cart-outline\" style=\"font-size: 28px;\"><\/i>\n                                            <\/a>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n                                    <a href=\"#inline\" id=\"11467\" class=\"icon ion-ios-search brick_more\" style=\"font-size: 28px;\"><\/a>\n                                    <!--<a href=\"#scheme\" id=\"scheme_11467\" class=\"icon ion-wrench brick_scheme\" style=\"font-size: 24px;\"><\/a>-->\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .back -->\n                        <\/div> <!--\/ .flipper -->\n\n                    <\/div> <!--\/ .flip-container -->\n                <\/div> <!--\/ .col-sm-2 -->\n\n\t\t\t\n\t\t\t\t\n                <div class=\"col-lg-2 col-md-4 col-xs-6\" style=\"margin-bottom: 16px;\">\n                    <div class=\"flip-container\" ontouchstart=\"this.classList.toggle('hover');\" style=\"text-align: center;\">\n                        <div class=\"flipper\">\n                            <div class=\"front\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto;\">\n\n                                    <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/wiki.brickrknowledge.com\/content\/uploads\/2015\/04\/Pic_ALL-BRICK-01431-150x150.jpg\" alt=\"\"\/>\n\n\n                                <\/div> <!--\/ .productImg -->\n\n                                <div class=\"productText\" style=\"margin-top: 16px;\">\n                                    <span class=\"amount\">\n\t\t\t\t\t\t\t\t\t\tx\t\t\t\t\t\t\t\t\t<\/span>\n\n                                    <h4 style=\"margin-top: 0; font-size: 14px;\">\n\t\t\t\t\t\t\t\t\t\tCarcasa pl\u00e1stico transparente 1&#215;1, Pack de 10                                    <\/h4>\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .front -->\n\n                            <div class=\"back\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto 16px auto;\">\n\t\t\t\t\t\t\t\t\t                                        <img decoding=\"async\" class=\"img-responsive\" src=\"\" alt=\" - Art.-ID: 116135\" style=\"margin: 0 auto;\" \/>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                <\/div>\n\n                                <div class=\"productText\" style=\"\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t                                            <a href=\"https:\/\/shop.maker-store.de\/ArtByOrdernumber\/forward\/article\/116135\" target=\"_blank\">\n                                                <i class=\"icon ion-ios-cart-outline\" style=\"font-size: 28px;\"><\/i>\n                                            <\/a>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n                                    <a href=\"#inline\" id=\"11469\" class=\"icon ion-ios-search brick_more\" style=\"font-size: 28px;\"><\/a>\n                                    <!--<a href=\"#scheme\" id=\"scheme_11469\" class=\"icon ion-wrench brick_scheme\" style=\"font-size: 24px;\"><\/a>-->\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .back -->\n                        <\/div> <!--\/ .flipper -->\n\n                    <\/div> <!--\/ .flip-container -->\n                <\/div> <!--\/ .col-sm-2 -->\n\n\t\t\t\n\t\t\t\t\n                <div class=\"col-lg-2 col-md-4 col-xs-6\" style=\"margin-bottom: 16px;\">\n                    <div class=\"flip-container\" ontouchstart=\"this.classList.toggle('hover');\" style=\"text-align: center;\">\n                        <div class=\"flipper\">\n                            <div class=\"front\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto;\">\n\n                                    <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/wiki.brickrknowledge.com\/content\/uploads\/2016\/06\/2D6G8861-150x150.jpg\" alt=\"\"\/>\n\n\n                                <\/div> <!--\/ .productImg -->\n\n                                <div class=\"productText\" style=\"margin-top: 16px;\">\n                                    <span class=\"amount\">\n\t\t\t\t\t\t\t\t\t\tx\t\t\t\t\t\t\t\t\t<\/span>\n\n                                    <h4 style=\"margin-top: 0; font-size: 14px;\">\n\t\t\t\t\t\t\t\t\t\tConector BNC                                    <\/h4>\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .front -->\n\n                            <div class=\"back\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto 16px auto;\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/wiki.brickrknowledge.com\/content\/uploads\/2016\/06\/2D6G8861-150x150.jpg\" alt=\" - Art.-ID: \" style=\"margin: 0 auto;\" \/>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                <\/div>\n\n                                <div class=\"productText\" style=\"\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t                                            <a href=\"https:\/\/shop.maker-store.de\/elektronik-experimente\/\" target=\"_blank\">\n                                                <i class=\"icon ion-ios-cart-outline\" style=\"font-size: 28px;\"><\/i>\n                                            <\/a>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n                                    <a href=\"#inline\" id=\"14845\" class=\"icon ion-ios-search brick_more\" style=\"font-size: 28px;\"><\/a>\n                                    <!--<a href=\"#scheme\" id=\"scheme_14845\" class=\"icon ion-wrench brick_scheme\" style=\"font-size: 24px;\"><\/a>-->\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .back -->\n                        <\/div> <!--\/ .flipper -->\n\n                    <\/div> <!--\/ .flip-container -->\n                <\/div> <!--\/ .col-sm-2 -->\n\n\t\t\t\n\t\t\t\t\n                <div class=\"col-lg-2 col-md-4 col-xs-6\" style=\"margin-bottom: 16px;\">\n                    <div class=\"flip-container\" ontouchstart=\"this.classList.toggle('hover');\" style=\"text-align: center;\">\n                        <div class=\"flipper\">\n                            <div class=\"front\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto;\">\n\n                                    <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/wiki.brickrknowledge.com\/content\/uploads\/2016\/06\/2D6G8853-150x150.jpg\" alt=\"\"\/>\n\n\n                                <\/div> <!--\/ .productImg -->\n\n                                <div class=\"productText\" style=\"margin-top: 16px;\">\n                                    <span class=\"amount\">\n\t\t\t\t\t\t\t\t\t\tx\t\t\t\t\t\t\t\t\t<\/span>\n\n                                    <h4 style=\"margin-top: 0; font-size: 14px;\">\n\t\t\t\t\t\t\t\t\t\tConector P-SMP                                    <\/h4>\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .front -->\n\n                            <div class=\"back\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto 16px auto;\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/wiki.brickrknowledge.com\/content\/uploads\/2016\/06\/2D6G8853-150x150.jpg\" alt=\" - Art.-ID: \" style=\"margin: 0 auto;\" \/>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                <\/div>\n\n                                <div class=\"productText\" style=\"\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t                                            <a href=\"https:\/\/shop.maker-store.de\/elektronik-experimente\/\" target=\"_blank\">\n                                                <i class=\"icon ion-ios-cart-outline\" style=\"font-size: 28px;\"><\/i>\n                                            <\/a>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n                                    <a href=\"#inline\" id=\"14867\" class=\"icon ion-ios-search brick_more\" style=\"font-size: 28px;\"><\/a>\n                                    <!--<a href=\"#scheme\" id=\"scheme_14867\" class=\"icon ion-wrench brick_scheme\" style=\"font-size: 24px;\"><\/a>-->\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .back -->\n                        <\/div> <!--\/ .flipper -->\n\n                    <\/div> <!--\/ .flip-container -->\n                <\/div> <!--\/ .col-sm-2 -->\n\n\t\t\t\n\t\t\t\t\n                <div class=\"col-lg-2 col-md-4 col-xs-6\" style=\"margin-bottom: 16px;\">\n                    <div class=\"flip-container\" ontouchstart=\"this.classList.toggle('hover');\" style=\"text-align: center;\">\n                        <div class=\"flipper\">\n                            <div class=\"front\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto;\">\n\n                                    <img decoding=\"async\" class=\"img-responsive\" src=\"\" alt=\"\"\/>\n\n\n                                <\/div> <!--\/ .productImg -->\n\n                                <div class=\"productText\" style=\"margin-top: 16px;\">\n                                    <span class=\"amount\">\n\t\t\t\t\t\t\t\t\t\tx\t\t\t\t\t\t\t\t\t<\/span>\n\n                                    <h4 style=\"margin-top: 0; font-size: 14px;\">\n\t\t\t\t\t\t\t\t\t\tInterconector P-SMP                                    <\/h4>\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .front -->\n\n                            <div class=\"back\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto 16px auto;\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                        <img decoding=\"async\" class=\"img-responsive\" src=\"\" alt=\" - Art.-ID: \" style=\"margin: 0 auto;\" \/>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                <\/div>\n\n                                <div class=\"productText\" style=\"\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t                                            <a href=\"https:\/\/shop.maker-store.de\/elektronik-experimente\/\" target=\"_blank\">\n                                                <i class=\"icon ion-ios-cart-outline\" style=\"font-size: 28px;\"><\/i>\n                                            <\/a>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n                                    <a href=\"#inline\" id=\"14868\" class=\"icon ion-ios-search brick_more\" style=\"font-size: 28px;\"><\/a>\n                                    <!--<a href=\"#scheme\" id=\"scheme_14868\" class=\"icon ion-wrench brick_scheme\" style=\"font-size: 24px;\"><\/a>-->\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .back -->\n                        <\/div> <!--\/ .flipper -->\n\n                    <\/div> <!--\/ .flip-container -->\n                <\/div> <!--\/ .col-sm-2 -->\n\n\t\t\t\n\t\t\t\t\n                <div class=\"col-lg-2 col-md-4 col-xs-6\" style=\"margin-bottom: 16px;\">\n                    <div class=\"flip-container\" ontouchstart=\"this.classList.toggle('hover');\" style=\"text-align: center;\">\n                        <div class=\"flipper\">\n                            <div class=\"front\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto;\">\n\n                                    <img decoding=\"async\" class=\"img-responsive\" src=\"\" alt=\"\"\/>\n\n\n                                <\/div> <!--\/ .productImg -->\n\n                                <div class=\"productText\" style=\"margin-top: 16px;\">\n                                    <span class=\"amount\">\n\t\t\t\t\t\t\t\t\t\tx\t\t\t\t\t\t\t\t\t<\/span>\n\n                                    <h4 style=\"margin-top: 0; font-size: 14px;\">\n\t\t\t\t\t\t\t\t\t\tManual Set MHz DIY                                    <\/h4>\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .front -->\n\n                            <div class=\"back\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto 16px auto;\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/wiki.brickrknowledge.com\/content\/themes\/allbrick\/dist\/img\/no_image.png\" alt=\" - Art.-ID: \" style=\"margin: 0 auto;\" \/>\n\t\t\t\t\t\t\t\t\t                                <\/div>\n\n                                <div class=\"productText\" style=\"\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t                                            <a href=\"https:\/\/shop.maker-store.de\/elektronik-experimente\/\" target=\"_blank\">\n                                                <i class=\"icon ion-ios-cart-outline\" style=\"font-size: 28px;\"><\/i>\n                                            <\/a>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n                                    <a href=\"#inline\" id=\"14842\" class=\"icon ion-ios-search brick_more\" style=\"font-size: 28px;\"><\/a>\n                                    <!--<a href=\"#scheme\" id=\"scheme_14842\" class=\"icon ion-wrench brick_scheme\" style=\"font-size: 24px;\"><\/a>-->\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .back -->\n                        <\/div> <!--\/ .flipper -->\n\n                    <\/div> <!--\/ .flip-container -->\n                <\/div> <!--\/ .col-sm-2 -->\n\n\t\t\t\n\t\t\t\t\n                <div class=\"col-lg-2 col-md-4 col-xs-6\" style=\"margin-bottom: 16px;\">\n                    <div class=\"flip-container\" ontouchstart=\"this.classList.toggle('hover');\" style=\"text-align: center;\">\n                        <div class=\"flipper\">\n                            <div class=\"front\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto;\">\n\n                                    <img decoding=\"async\" class=\"img-responsive\" src=\"\" alt=\"\"\/>\n\n\n                                <\/div> <!--\/ .productImg -->\n\n                                <div class=\"productText\" style=\"margin-top: 16px;\">\n                                    <span class=\"amount\">\n\t\t\t\t\t\t\t\t\t\tx\t\t\t\t\t\t\t\t\t<\/span>\n\n                                    <h4 style=\"margin-top: 0; font-size: 14px;\">\n\t\t\t\t\t\t\t\t\t\tPieza intermedia transparente                                    <\/h4>\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .front -->\n\n                            <div class=\"back\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto 16px auto;\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/wiki.brickrknowledge.com\/content\/themes\/allbrick\/dist\/img\/no_image.png\" alt=\" - Art.-ID: \" style=\"margin: 0 auto;\" \/>\n\t\t\t\t\t\t\t\t\t                                <\/div>\n\n                                <div class=\"productText\" style=\"\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t                                            <a href=\"https:\/\/shop.maker-store.de\/elektronik-experimente\/\" target=\"_blank\">\n                                                <i class=\"icon ion-ios-cart-outline\" style=\"font-size: 28px;\"><\/i>\n                                            <\/a>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n                                    <a href=\"#inline\" id=\"14844\" class=\"icon ion-ios-search brick_more\" style=\"font-size: 28px;\"><\/a>\n                                    <!--<a href=\"#scheme\" id=\"scheme_14844\" class=\"icon ion-wrench brick_scheme\" style=\"font-size: 24px;\"><\/a>-->\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .back -->\n                        <\/div> <!--\/ .flipper -->\n\n                    <\/div> <!--\/ .flip-container -->\n                <\/div> <!--\/ .col-sm-2 -->\n\n\t\t\t\n\t\t\t\t\n                <div class=\"col-lg-2 col-md-4 col-xs-6\" style=\"margin-bottom: 16px;\">\n                    <div class=\"flip-container\" ontouchstart=\"this.classList.toggle('hover');\" style=\"text-align: center;\">\n                        <div class=\"flipper\">\n                            <div class=\"front\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto;\">\n\n                                    <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/wiki.brickrknowledge.com\/content\/uploads\/2015\/04\/Pic_ALL-BRICK-03201-150x150.jpg\" alt=\"\"\/>\n\n\n                                <\/div> <!--\/ .productImg -->\n\n                                <div class=\"productText\" style=\"margin-top: 16px;\">\n                                    <span class=\"amount\">\n\t\t\t\t\t\t\t\t\t\tx\t\t\t\t\t\t\t\t\t<\/span>\n\n                                    <h4 style=\"margin-top: 0; font-size: 14px;\">\n\t\t\t\t\t\t\t\t\t\tPiezas de conexi\u00f3n                                    <\/h4>\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .front -->\n\n                            <div class=\"back\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto 16px auto;\">\n\t\t\t\t\t\t\t\t\t                                        <img decoding=\"async\" class=\"img-responsive\" src=\"\" alt=\" - Art.-ID: 120887\" style=\"margin: 0 auto;\" \/>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                <\/div>\n\n                                <div class=\"productText\" style=\"\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t                                            <a href=\"https:\/\/shop.maker-store.de\/ArtByOrdernumber\/forward\/article\/120887\" target=\"_blank\">\n                                                <i class=\"icon ion-ios-cart-outline\" style=\"font-size: 28px;\"><\/i>\n                                            <\/a>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n                                    <a href=\"#inline\" id=\"11459\" class=\"icon ion-ios-search brick_more\" style=\"font-size: 28px;\"><\/a>\n                                    <!--<a href=\"#scheme\" id=\"scheme_11459\" class=\"icon ion-wrench brick_scheme\" style=\"font-size: 24px;\"><\/a>-->\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .back -->\n                        <\/div> <!--\/ .flipper -->\n\n                    <\/div> <!--\/ .flip-container -->\n                <\/div> <!--\/ .col-sm-2 -->\n\n\t\t\t\n\t\t\t\t\n                <div class=\"col-lg-2 col-md-4 col-xs-6\" style=\"margin-bottom: 16px;\">\n                    <div class=\"flip-container\" ontouchstart=\"this.classList.toggle('hover');\" style=\"text-align: center;\">\n                        <div class=\"flipper\">\n                            <div class=\"front\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto;\">\n\n                                    <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/wiki.brickrknowledge.com\/content\/uploads\/2016\/06\/130196-150x150.jpg\" alt=\"\"\/>\n\n\n                                <\/div> <!--\/ .productImg -->\n\n                                <div class=\"productText\" style=\"margin-top: 16px;\">\n                                    <span class=\"amount\">\n\t\t\t\t\t\t\t\t\t\tx\t\t\t\t\t\t\t\t\t<\/span>\n\n                                    <h4 style=\"margin-top: 0; font-size: 14px;\">\n\t\t\t\t\t\t\t\t\t\tPlaca EMODGBNC1 GHz                                    <\/h4>\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .front -->\n\n                            <div class=\"back\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto 16px auto;\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/wiki.brickrknowledge.com\/content\/uploads\/2016\/06\/130196_2-150x150.jpg\" alt=\" - Art.-ID: 130196\" style=\"margin: 0 auto;\" \/>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                <\/div>\n\n                                <div class=\"productText\" style=\"\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t                                            <a href=\"https:\/\/shop.maker-store.de\/ArtByOrdernumber\/forward\/article\/130196\" target=\"_blank\">\n                                                <i class=\"icon ion-ios-cart-outline\" style=\"font-size: 28px;\"><\/i>\n                                            <\/a>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n                                    <a href=\"#inline\" id=\"14873\" class=\"icon ion-ios-search brick_more\" style=\"font-size: 28px;\"><\/a>\n                                    <!--<a href=\"#scheme\" id=\"scheme_14873\" class=\"icon ion-wrench brick_scheme\" style=\"font-size: 24px;\"><\/a>-->\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .back -->\n                        <\/div> <!--\/ .flipper -->\n\n                    <\/div> <!--\/ .flip-container -->\n                <\/div> <!--\/ .col-sm-2 -->\n\n\t\t\t\n\t\t\t\t\n                <div class=\"col-lg-2 col-md-4 col-xs-6\" style=\"margin-bottom: 16px;\">\n                    <div class=\"flip-container\" ontouchstart=\"this.classList.toggle('hover');\" style=\"text-align: center;\">\n                        <div class=\"flipper\">\n                            <div class=\"front\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto;\">\n\n                                    <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/wiki.brickrknowledge.com\/content\/uploads\/2016\/06\/124256_2-150x150.jpg\" alt=\"\"\/>\n\n\n                                <\/div> <!--\/ .productImg -->\n\n                                <div class=\"productText\" style=\"margin-top: 16px;\">\n                                    <span class=\"amount\">\n\t\t\t\t\t\t\t\t\t\tx\t\t\t\t\t\t\t\t\t<\/span>\n\n                                    <h4 style=\"margin-top: 0; font-size: 14px;\">\n\t\t\t\t\t\t\t\t\t\tPlaca EMODGRAST GHz                                    <\/h4>\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .front -->\n\n                            <div class=\"back\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto 16px auto;\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/wiki.brickrknowledge.com\/content\/uploads\/2016\/06\/124256-150x150.jpg\" alt=\" - Art.-ID: 124256\" style=\"margin: 0 auto;\" \/>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                <\/div>\n\n                                <div class=\"productText\" style=\"\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t                                            <a href=\"https:\/\/shop.maker-store.de\/ArtByOrdernumber\/forward\/article\/124256\" target=\"_blank\">\n                                                <i class=\"icon ion-ios-cart-outline\" style=\"font-size: 28px;\"><\/i>\n                                            <\/a>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n                                    <a href=\"#inline\" id=\"14875\" class=\"icon ion-ios-search brick_more\" style=\"font-size: 28px;\"><\/a>\n                                    <!--<a href=\"#scheme\" id=\"scheme_14875\" class=\"icon ion-wrench brick_scheme\" style=\"font-size: 24px;\"><\/a>-->\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .back -->\n                        <\/div> <!--\/ .flipper -->\n\n                    <\/div> <!--\/ .flip-container -->\n                <\/div> <!--\/ .col-sm-2 -->\n\n\t\t\t\n\t\t\t\t\n                <div class=\"col-lg-2 col-md-4 col-xs-6\" style=\"margin-bottom: 16px;\">\n                    <div class=\"flip-container\" ontouchstart=\"this.classList.toggle('hover');\" style=\"text-align: center;\">\n                        <div class=\"flipper\">\n                            <div class=\"front\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto;\">\n\n                                    <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/wiki.brickrknowledge.com\/content\/uploads\/2016\/06\/128899-150x150.jpg\" alt=\"\"\/>\n\n\n                                <\/div> <!--\/ .productImg -->\n\n                                <div class=\"productText\" style=\"margin-top: 16px;\">\n                                    <span class=\"amount\">\n\t\t\t\t\t\t\t\t\t\tx\t\t\t\t\t\t\t\t\t<\/span>\n\n                                    <h4 style=\"margin-top: 0; font-size: 14px;\">\n\t\t\t\t\t\t\t\t\t\tPlaca EMODGRST2 GHz                                    <\/h4>\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .front -->\n\n                            <div class=\"back\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto 16px auto;\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                        <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/wiki.brickrknowledge.com\/content\/uploads\/2016\/06\/128899_2-150x150.jpg\" alt=\" - Art.-ID: 128899\" style=\"margin: 0 auto;\" \/>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                <\/div>\n\n                                <div class=\"productText\" style=\"\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t                                            <a href=\"https:\/\/shop.maker-store.de\/ArtByOrdernumber\/forward\/article\/128899\" target=\"_blank\">\n                                                <i class=\"icon ion-ios-cart-outline\" style=\"font-size: 28px;\"><\/i>\n                                            <\/a>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n                                    <a href=\"#inline\" id=\"14874\" class=\"icon ion-ios-search brick_more\" style=\"font-size: 28px;\"><\/a>\n                                    <!--<a href=\"#scheme\" id=\"scheme_14874\" class=\"icon ion-wrench brick_scheme\" style=\"font-size: 24px;\"><\/a>-->\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .back -->\n                        <\/div> <!--\/ .flipper -->\n\n                    <\/div> <!--\/ .flip-container -->\n                <\/div> <!--\/ .col-sm-2 -->\n\n\t\t\t\n\t\t\t\t\n                <div class=\"col-lg-2 col-md-4 col-xs-6\" style=\"margin-bottom: 16px;\">\n                    <div class=\"flip-container\" ontouchstart=\"this.classList.toggle('hover');\" style=\"text-align: center;\">\n                        <div class=\"flipper\">\n                            <div class=\"front\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto;\">\n\n                                    <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/wiki.brickrknowledge.com\/content\/uploads\/2015\/08\/leere_4-150x150.jpg\" alt=\"\"\/>\n\n\n                                <\/div> <!--\/ .productImg -->\n\n                                <div class=\"productText\" style=\"margin-top: 16px;\">\n                                    <span class=\"amount\">\n\t\t\t\t\t\t\t\t\t\tx\t\t\t\t\t\t\t\t\t<\/span>\n\n                                    <h4 style=\"margin-top: 0; font-size: 14px;\">\n\t\t\t\t\t\t\t\t\t\tPlantilla de soldadura                                    <\/h4>\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .front -->\n\n                            <div class=\"back\">\n\n                                <div class=\"productImg\" style=\"width: 70px; margin: 0 auto 16px auto;\">\n\t\t\t\t\t\t\t\t\t                                        <img decoding=\"async\" class=\"img-responsive\" src=\"\" alt=\" - Art.-ID: \" style=\"margin: 0 auto;\" \/>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t                                <\/div>\n\n                                <div class=\"productText\" style=\"\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t                                            <a href=\"https:\/\/shop.maker-store.de\/elektronik-experimente\/\" target=\"_blank\">\n                                                <i class=\"icon ion-ios-cart-outline\" style=\"font-size: 28px;\"><\/i>\n                                            <\/a>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n                                    <a href=\"#inline\" id=\"11475\" class=\"icon ion-ios-search brick_more\" style=\"font-size: 28px;\"><\/a>\n                                    <!--<a href=\"#scheme\" id=\"scheme_11475\" class=\"icon ion-wrench brick_scheme\" style=\"font-size: 24px;\"><\/a>-->\n                                <\/div> <!--\/ .productText -->\n                            <\/div> <!--\/ .back -->\n                        <\/div> <!--\/ .flipper -->\n\n                    <\/div> <!--\/ .flip-container -->\n                <\/div> <!--\/ .col-sm-2 -->\n\n\t\t\t\t\t\t        <\/div> <!--\/ .row -->\n    <\/div> <!--\/ flipper -->\n    <\/div>\n\n\n\n\n\t\t\t\n\n\t\t<\/div>\n\t<\/div>\n\n\t\n","protected":false},"excerpt":{"rendered":"<p>El Set DIY MHz contiene todo lo que se necesita para realizar circuitos ambiciosos en el rango de MHz. El Set incluye 4 placas, de las cuales 1 lleva Roger RO4350 de alta calidad. Las placas FR4 son adecuadas para hasta 2,4GHz. Las diferentes placas se pueden utilizar para construir splitter, combinadores, filtros, mezcladores, adaptadores, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":15915,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page_sets.php","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-12355","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Set DIY MHz - Brick&#039;R&#039;knowledge<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.brickrknowledge.com\/es\/sets\/diy\/mhz-diy-set\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Set DIY MHz - Brick&#039;R&#039;knowledge\" \/>\n<meta property=\"og:description\" content=\"El Set DIY MHz contiene todo lo que se necesita para realizar circuitos ambiciosos en el rango de MHz. El Set incluye 4 placas, de las cuales 1 lleva Roger RO4350 de alta calidad. Las placas FR4 son adecuadas para hasta 2,4GHz. Las diferentes placas se pueden utilizar para construir splitter, combinadores, filtros, mezcladores, adaptadores, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.brickrknowledge.com\/es\/sets\/diy\/mhz-diy-set\/\" \/>\n<meta property=\"og:site_name\" content=\"Brick&#039;R&#039;knowledge\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BrickRknowledge\" \/>\n<meta property=\"article:modified_time\" content=\"2017-07-27T11:41:02+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@brickrknowledge\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.brickrknowledge.com\/es\/sets\/diy\/mhz-diy-set\/\",\"url\":\"https:\/\/www.brickrknowledge.com\/es\/sets\/diy\/mhz-diy-set\/\",\"name\":\"Set DIY MHz - Brick&#039;R&#039;knowledge\",\"isPartOf\":{\"@id\":\"https:\/\/www.brickrknowledge.com\/#website\"},\"datePublished\":\"2016-08-31T11:06:35+00:00\",\"dateModified\":\"2017-07-27T11:41:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.brickrknowledge.com\/es\/sets\/diy\/mhz-diy-set\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.brickrknowledge.com\/es\/sets\/diy\/mhz-diy-set\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.brickrknowledge.com\/es\/sets\/diy\/mhz-diy-set\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/wiki.brickrknowledge.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sets\",\"item\":\"https:\/\/forum.brickrknowledge.com\/es\/sets\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"DIY\",\"item\":\"https:\/\/www.brickrknowledge.com\/es\/sets\/diy\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Set DIY MHz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.brickrknowledge.com\/#website\",\"url\":\"https:\/\/www.brickrknowledge.com\/\",\"name\":\"Brick&#039;R&#039;knowledge\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.brickrknowledge.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Set DIY MHz - Brick&#039;R&#039;knowledge","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.brickrknowledge.com\/es\/sets\/diy\/mhz-diy-set\/","og_locale":"es_ES","og_type":"article","og_title":"Set DIY MHz - Brick&#039;R&#039;knowledge","og_description":"El Set DIY MHz contiene todo lo que se necesita para realizar circuitos ambiciosos en el rango de MHz. El Set incluye 4 placas, de las cuales 1 lleva Roger RO4350 de alta calidad. Las placas FR4 son adecuadas para hasta 2,4GHz. Las diferentes placas se pueden utilizar para construir splitter, combinadores, filtros, mezcladores, adaptadores, [&hellip;]","og_url":"https:\/\/www.brickrknowledge.com\/es\/sets\/diy\/mhz-diy-set\/","og_site_name":"Brick&#039;R&#039;knowledge","article_publisher":"https:\/\/www.facebook.com\/BrickRknowledge","article_modified_time":"2017-07-27T11:41:02+00:00","twitter_card":"summary_large_image","twitter_site":"@brickrknowledge","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.brickrknowledge.com\/es\/sets\/diy\/mhz-diy-set\/","url":"https:\/\/www.brickrknowledge.com\/es\/sets\/diy\/mhz-diy-set\/","name":"Set DIY MHz - Brick&#039;R&#039;knowledge","isPartOf":{"@id":"https:\/\/www.brickrknowledge.com\/#website"},"datePublished":"2016-08-31T11:06:35+00:00","dateModified":"2017-07-27T11:41:02+00:00","breadcrumb":{"@id":"https:\/\/www.brickrknowledge.com\/es\/sets\/diy\/mhz-diy-set\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.brickrknowledge.com\/es\/sets\/diy\/mhz-diy-set\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.brickrknowledge.com\/es\/sets\/diy\/mhz-diy-set\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wiki.brickrknowledge.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Sets","item":"https:\/\/forum.brickrknowledge.com\/es\/sets\/"},{"@type":"ListItem","position":3,"name":"DIY","item":"https:\/\/www.brickrknowledge.com\/es\/sets\/diy\/"},{"@type":"ListItem","position":4,"name":"Set DIY MHz"}]},{"@type":"WebSite","@id":"https:\/\/www.brickrknowledge.com\/#website","url":"https:\/\/www.brickrknowledge.com\/","name":"Brick&#039;R&#039;knowledge","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.brickrknowledge.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-ES"}]}},"_links":{"self":[{"href":"https:\/\/wiki.brickrknowledge.com\/es\/wp-json\/wp\/v2\/pages\/12355"}],"collection":[{"href":"https:\/\/wiki.brickrknowledge.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wiki.brickrknowledge.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wiki.brickrknowledge.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/wiki.brickrknowledge.com\/es\/wp-json\/wp\/v2\/comments?post=12355"}],"version-history":[{"count":0,"href":"https:\/\/wiki.brickrknowledge.com\/es\/wp-json\/wp\/v2\/pages\/12355\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/wiki.brickrknowledge.com\/es\/wp-json\/wp\/v2\/pages\/15915"}],"wp:attachment":[{"href":"https:\/\/wiki.brickrknowledge.com\/es\/wp-json\/wp\/v2\/media?parent=12355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wiki.brickrknowledge.com\/es\/wp-json\/wp\/v2\/categories?post=12355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wiki.brickrknowledge.com\/es\/wp-json\/wp\/v2\/tags?post=12355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}